{"id":38972,"date":"2026-04-17T14:26:55","date_gmt":"2026-04-17T12:26:55","guid":{"rendered":"https:\/\/www.ce-illkirch.fr\/wordpress\/?p=38972"},"modified":"2026-04-17T14:26:55","modified_gmt":"2026-04-17T12:26:55","slug":"ca-bourgeonne-a-la-ludotheque","status":"publish","type":"post","link":"https:\/\/www.ce-illkirch.fr\/wordpress\/2026\/04\/bibliotheque\/ca-bourgeonne-a-la-ludotheque\/","title":{"rendered":"Ca bourgeonne \u00e0 la ludoth\u00e8que"},"content":{"rendered":"<p>Avec plein de nouveaux jeux:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-38976 alignleft\" src=\"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/toy-graphics-boxbottom-game-1744636033ecoem-300x236.png\" alt=\"\" width=\"376\" height=\"296\" srcset=\"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/toy-graphics-boxbottom-game-1744636033ecoem-300x236.png 300w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/toy-graphics-boxbottom-game-1744636033ecoem-1024x804.png 1024w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/toy-graphics-boxbottom-game-1744636033ecoem-768x603.png 768w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/toy-graphics-boxbottom-game-1744636033ecoem-1536x1206.png 1536w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/toy-graphics-boxbottom-game-1744636033ecoem-110x86.png 110w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/toy-graphics-boxbottom-game-1744636033ecoem-420x330.png 420w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/toy-graphics-boxbottom-game-1744636033ecoem-548x430.png 548w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/toy-graphics-boxbottom-game-1744636033ecoem.png 1885w\" sizes=\"auto, (max-width: 376px) 100vw, 376px\" \/><\/p>\n<h3>Toy Battle<\/h3>\n<p>2 joueurs, 8 ans et plus, partie de 15&prime;<\/p>\n<p>Sur terre, en mer, dans les nuages et m\u00eame dans l\u2019espace, les batailles se multiplient chez les jouets : ils ont besoin de vous !<br \/>\nMan\u0153uvrez vos troupes et utilisez astucieusement leurs effets pour prendre l\u2019avantage sur votre adversaire.<br \/>\nVotre mission ? Capturer le quartier g\u00e9n\u00e9ral ennemi ou remporter un maximum de m\u00e9dailles.<br \/>\nPr\u00e9parez-vous \u00e0 un affrontement sans piti\u00e9 !<\/p>\n<p><a href=\"https:\/\/www.rprod.com\/fr\/games\/toy-battle\">https:\/\/www.rprod.com\/fr\/games\/toy-battle<\/a><\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=D7uEBhEY9TM\">https:\/\/www.youtube.com\/watch?v=D7uEBhEY9TM<\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-38974 \" src=\"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/zenith-300x300.jpg\" alt=\"\" width=\"445\" height=\"445\" srcset=\"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/zenith-300x300.jpg 300w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/zenith-150x150.jpg 150w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/zenith-768x768.jpg 768w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/zenith-250x250.jpg 250w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/zenith-125x125.jpg 125w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/zenith-110x110.jpg 110w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/zenith-420x420.jpg 420w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/zenith-430x430.jpg 430w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/zenith-120x120.jpg 120w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/zenith.jpg 1024w\" sizes=\"auto, (max-width: 445px) 100vw, 445px\" \/><\/h3>\n<h3>Zenith<\/h3>\n<p>2 ou 4 joueurs, 10 ans et plus, partie de 30&prime;<\/p>\n<p>Vainqueur de l&rsquo;As d&rsquo;Or 2026 &#8211; cat\u00e9gorie initi\u00e9.<br \/>\nQui prendra le contr\u00f4le du syst\u00e8me solaire ?<br \/>\nZ\u00e9nith est un jeu tactique con\u00e7u pour 2 joueurs ou pour 4 joueurs en \u00e9quipes.<br \/>\nDans cet affrontement strat\u00e9gique, chaque camp se lance dans une lutte pour s\u2019imposer sur les 5 plan\u00e8tes du syst\u00e8me solaire.<br \/>\nPouvoir, diplomatie et d\u00e9veloppement technologique : toutes les strat\u00e9gies sont permises pour d\u00e9crocher la victoire.<\/p>\n<p>Avec un gameplay rapide \u00e0 comprendre mais profond\u00e9ment strat\u00e9gique, Z\u00e9nith vous plonge dans une lutte pour contr\u00f4ler le syst\u00e8me solaire ou chaque choix compte.<\/p>\n<p>Gr\u00e2ce \u00e0 son syst\u00e8me de \u00ab\u00a0tir \u00e0 la corde\u00a0\u00bb, chaque mouvement rapproche votre camp de la victoire\u2026 ou peut tout faire basculer.<br \/>\nSaurez-vous \u00e9quilibrer tactique et prise de risque pour dominer vos adversaires ?<\/p>\n<p>Z\u00e9nith, c\u2019est l\u2019alliance parfaite entre r\u00e9flexion, tension et plaisir de jeu. Relevez le d\u00e9fi et prenez le contr\u00f4le du syst\u00e8me solaire !<\/p>\n<p><a href=\"https:\/\/shop.asmodee.fr\/zenith-plpzen01fr\">https:\/\/shop.asmodee.fr\/zenith-plpzen01fr<\/a><br \/>\n<a href=\"https:\/\/www.youtube.com\/watch?v=cKjOd1lekeY\">https:\/\/www.youtube.com\/watch?v=cKjOd1lekeY<\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-38975 alignleft\" src=\"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/exit-puzzle-le-phare-solitaire-jeu-presentation.png\" alt=\"\" width=\"503\" height=\"364\" srcset=\"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/exit-puzzle-le-phare-solitaire-jeu-presentation.png 1150w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/exit-puzzle-le-phare-solitaire-jeu-presentation-300x217.png 300w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/exit-puzzle-le-phare-solitaire-jeu-presentation-1024x740.png 1024w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/exit-puzzle-le-phare-solitaire-jeu-presentation-768x555.png 768w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/exit-puzzle-le-phare-solitaire-jeu-presentation-110x79.png 110w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/exit-puzzle-le-phare-solitaire-jeu-presentation-420x303.png 420w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/exit-puzzle-le-phare-solitaire-jeu-presentation-595x430.png 595w\" sizes=\"auto, (max-width: 503px) 100vw, 503px\" \/><\/h3>\n<h3>Exit Puzzle : Le Phare Solitaire<\/h3>\n<p>1 \u00e0 4 joueurs,\u00a0 12 ans et plus, partie de 30 \u00e0 45&prime;<\/p>\n<p>EXIT Puzzle, ce sont des aventures Escape Game avec des \u00e9nigmes \u00e0 r\u00e9soudre&#8230; et des puzzles \u00e0 reconstituer !<\/p>\n<p>Cela fait des heures que vous cherchez d\u00e9sesp\u00e9r\u00e9ment un abri contre la temp\u00eate qui fait rage.<br \/>\nTremp\u00e9 jusqu\u2019aux os, vous errez le long de la c\u00f4te lorsque soudain, un vif halo vient \u00e9clairer les t\u00e9n\u00e8bres : vous avez d\u00e9couvert un phare !<br \/>\nMais, brusquement, la lumi\u00e8re s\u2019\u00e9teint, et vous apercevez un bateau qui fonce droit sur les rochers.<br \/>\nIl n\u2019y a qu\u2019une chose \u00e0 faire : p\u00e9n\u00e9trer au plus vite dans la tour pour remettre la lumi\u00e8re en marche avant que le navire ne s\u2019\u00e9crase !<\/p>\n<p><a href=\"https:\/\/iello.fr\/jeux\/exit-puzzle-le-phare-solitaire\/?_sm_nck=1\">https:\/\/iello.fr\/jeux\/exit-puzzle-le-phare-solitaire\/?_sm_nck=1<\/a><br \/>\n<a href=\"https:\/\/www.youtube.com\/watch?v=9bxk0fFuMDk\">https:\/\/www.youtube.com\/watch?v=9bxk0fFuMDk<\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-38979 alignleft\" src=\"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/Pili_Pili_2_Cartas__76555.webp\" alt=\"\" width=\"301\" height=\"301\" srcset=\"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/Pili_Pili_2_Cartas__76555.webp 1000w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/Pili_Pili_2_Cartas__76555-300x300.webp 300w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/Pili_Pili_2_Cartas__76555-150x150.webp 150w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/Pili_Pili_2_Cartas__76555-768x768.webp 768w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/Pili_Pili_2_Cartas__76555-250x250.webp 250w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/Pili_Pili_2_Cartas__76555-125x125.webp 125w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/Pili_Pili_2_Cartas__76555-110x110.webp 110w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/Pili_Pili_2_Cartas__76555-420x420.webp 420w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/Pili_Pili_2_Cartas__76555-430x430.webp 430w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/Pili_Pili_2_Cartas__76555-120x120.webp 120w\" sizes=\"auto, (max-width: 301px) 100vw, 301px\" \/><\/p>\n<h3>Pili pili<\/h3>\n<p>2 \u00e0 8 joueurs, 8 ans et plus, partie de 20&prime;<\/p>\n<p>Frottez-vous \u00e0 ce jeu de plis bien relev\u00e9..!<br \/>\nPili Pili est un jeu de cartes et de plis pour 2 \u00e0 8 joueurs.<br \/>\nDans ce jeu de cartes, vous devrez parier sur le nombre de plis que vous pensez remporter, tout en vous adaptant \u00e0 des missions qui pimentent chaque manche.<br \/>\nPrendre des risques, ruser&#8230; ou savoir perdre au bon moment sera la cl\u00e9 !<\/p>\n<p><a href=\"https:\/\/atmgaming.com\/product\/pili-pili\">https:\/\/atmgaming.com\/product\/pili-pili<\/a><br \/>\n<a href=\"https:\/\/www.youtube.com\/watch?v=xGOTX-TNqS0\">https:\/\/www.youtube.com\/watch?v=xGOTX-TNqS0<\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-38977 alignleft\" src=\"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/au-cachot-ext-chateau-combo-p-image-104316-grande.webp\" alt=\"\" width=\"380\" height=\"285\" srcset=\"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/au-cachot-ext-chateau-combo-p-image-104316-grande.webp 1200w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/au-cachot-ext-chateau-combo-p-image-104316-grande-300x225.webp 300w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/au-cachot-ext-chateau-combo-p-image-104316-grande-1024x768.webp 1024w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/au-cachot-ext-chateau-combo-p-image-104316-grande-768x576.webp 768w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/au-cachot-ext-chateau-combo-p-image-104316-grande-110x83.webp 110w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/au-cachot-ext-chateau-combo-p-image-104316-grande-420x315.webp 420w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/au-cachot-ext-chateau-combo-p-image-104316-grande-573x430.webp 573w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/><\/p>\n<h3>Chateau combo extension Au cachot<\/h3>\n<p>2 \u00e0 5 joueurs, 10 ans et plus, partie de 25&prime;<\/p>\n<p>12 nouveaux personnages et effets cadenas !<br \/>\nCh\u00e2teau Combo : Au Cachot ! est une extension pour le jeu Ch\u00e2teau Combo.<br \/>\nVous y trouverez 12 nouveaux personnages pour de nouvelles combinaisons et une nouvelle m\u00e9canique d&rsquo;effets : les cadenas.<\/p>\n<p><a href=\"https:\/\/blackrockgames.fr\/game\/CAT107CH?_sm_nck=1\">https:\/\/blackrockgames.fr\/game\/CAT107CH?_sm_nck=1<\/a><br \/>\n<a href=\"https:\/\/www.youtube.com\/watch?v=gCldfb3aKE0\">https:\/\/www.youtube.com\/watch?v=gCldfb3aKE0<\/a><br \/>\n<a href=\"https:\/\/www.youtube.com\/watch?v=T-FFZcpiHdw\">https:\/\/www.youtube.com\/watch?v=T-FFZcpiHdw<\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-38980 alignleft\" src=\"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/presages-p-image-101692-grande.webp\" alt=\"\" width=\"306\" height=\"311\" srcset=\"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/presages-p-image-101692-grande.webp 1031w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/presages-p-image-101692-grande-295x300.webp 295w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/presages-p-image-101692-grande-1007x1024.webp 1007w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/presages-p-image-101692-grande-768x781.webp 768w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/presages-p-image-101692-grande-108x110.webp 108w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/presages-p-image-101692-grande-413x420.webp 413w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/presages-p-image-101692-grande-423x430.webp 423w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/p>\n<h3>Presages<\/h3>\n<p>4 \u00e0 6 joueurs,\u00a0 10 ans et plus, partie de 25&prime;<\/p>\n<p>L\u2019avenir est entre vos mains&#8230;<\/p>\n<p>Pr\u00e9sages est un jeu de cartes pour 4 \u00e0 6 joueurs.<br \/>\nDans ce jeu de soci\u00e9t\u00e9 qui se joue en \u00e9quipes, votre objectif est simple : permettre \u00e0 l\u2019un de vos co\u00e9quipiers d\u2019\u00eatre le premier \u00e0 n\u2019avoir plus qu\u2019une seule carte en main.<br \/>\nMais attention, chaque d\u00e9cision est importante, et vos adversaires feront tout pour vous en emp\u00eacher !<\/p>\n<p><a href=\"https:\/\/blackrockgames.fr\/game\/SPI007PR\">https:\/\/blackrockgames.fr\/game\/SPI007PR<\/a><br \/>\n<a href=\"https:\/\/www.youtube.com\/watch?v=7JF2pLOAV2g\">https:\/\/www.youtube.com\/watch?v=7JF2pLOAV2g<\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-38978 alignleft\" src=\"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/bellevue.webp\" alt=\"\" width=\"288\" height=\"288\" srcset=\"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/bellevue.webp 800w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/bellevue-300x300.webp 300w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/bellevue-150x150.webp 150w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/bellevue-768x768.webp 768w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/bellevue-250x250.webp 250w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/bellevue-125x125.webp 125w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/bellevue-110x110.webp 110w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/bellevue-420x420.webp 420w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/bellevue-430x430.webp 430w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/bellevue-120x120.webp 120w\" sizes=\"auto, (max-width: 288px) 100vw, 288px\" \/><\/p>\n<h3>Bellevue<\/h3>\n<p>2 \u00e0 5 joueurs, 8 ans et plus, partie de 20&prime;<\/p>\n<p>Bellevue est un jeu de pose de cartes agr\u00e9able dans lequel vous cr\u00e9ez votre rue en construisant des maisons d\u2019architecture flamande typique sur le canal d\u2019Amsterdam.<br \/>\nChoisissez la meilleure carte de votre main \u00e0 poser avant de les passer \u00e0 vos adversaires.<br \/>\nVous devrez r\u00e9aliser les objectifs de vos Boutiques et de vos Toits, tout en gardant un \u0153il sur les couleurs afin de marquer le plus de points et de remporter la victoire !<\/p>\n<p><a href=\"https:\/\/www.gigamic.com\/jeux-de-voyage\/1266-bellevue-3421277324519.html\">https:\/\/www.gigamic.com\/jeux-de-voyage\/1266-bellevue-3421277324519.html<\/a><br \/>\n<a href=\"https:\/\/www.youtube.com\/watch?v=yGtrm3An_Hk\">https:\/\/www.youtube.com\/watch?v=yGtrm3An_Hk<\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-38973 alignleft\" src=\"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/warden_keene.jpg\" alt=\"\" width=\"792\" height=\"482\" srcset=\"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/warden_keene.jpg 1024w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/warden_keene-300x183.jpg 300w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/warden_keene-768x467.jpg 768w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/warden_keene-110x67.jpg 110w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/warden_keene-420x256.jpg 420w, https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/03\/warden_keene-707x430.jpg 707w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/p>\n<h3>Les secrets de Warden Keene<\/h3>\n<p>1 \u00e0 4 joueurs, 10 ans et plus, partie de 10 \u00e0 30&prime;<\/p>\n<p>Warden Keene \u00e9tait le gardien du cimeti\u00e8re de Spoon River.<br \/>\nLes morts qui y gisent ont connu un destin tumultueux ; passions et ranc\u0153urs perturbent encore leur repos \u00e9ternel.<br \/>\nWarden a consign\u00e9 leurs secrets dans son journal, dont vous h\u00e9ritez aujourd\u2019hui.<br \/>\nA vous de mener l\u2019enqu\u00eate de tombe en tombe en d\u00e9cryptant les \u00e9pitaphes avec logique.<br \/>\nVous exhumerez au grand jour les 11 myst\u00e8res qui hantent ces lieux, \u00e0 l\u2019aide d\u2019un seul outil : votre sens de l\u2019observation.<br \/>\nFaites dialoguer les tombes en r\u00e9v\u00e9lant les histoires de leurs occupants. Pas de points, pas de scores, seul le plaisir de l&rsquo;enqu\u00eate.<br \/>\nLorsque vous \u00eates bloqu\u00e9s, une aide vous guide pas \u00e0 pas, sans g\u00e2cher la surprise. Le mat\u00e9riel de jeu, somptueux, vous plonge dans l&rsquo;atmosph\u00e8re unique d&rsquo;un cimeti\u00e8re du si\u00e8cle dernier.<br \/>\nInspir\u00e9 du recueil de po\u00e8mes Spoon River Anthology, ce jeu narratif coop\u00e9ratif est aussi fascinant qu&rsquo;ing\u00e9nieux.<\/p>\n<p><a href=\"https:\/\/shop.asmodee.fr\/les-secrets-de-warden-keene-bomwar01fr\">https:\/\/shop.asmodee.fr\/les-secrets-de-warden-keene-bomwar01fr<\/a><br \/>\n<a href=\"https:\/\/www.youtube.com\/watch?v=JAI4Zd3XpGY\">https:\/\/www.youtube.com\/watch?v=JAI4Zd3XpGY<\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Le r\u00e9sum\u00e9 des descriptions <a href=\"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/2026\/04\/Ludotheque-nouveautes-avril-resumes.pdf\">ici<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec plein de nouveaux jeux: Toy Battle 2 joueurs, 8 ans et plus, partie de 15&prime; Sur terre, en mer, dans les nuages et m\u00eame dans l\u2019espace, les batailles se [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":38990,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,19,112,36],"tags":[],"class_list":["post-38972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bibliotheque","category-19","category-nouveautes","category-top_banner"],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 08:43:12","action":"category","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/posts\/38972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=38972"}],"version-history":[{"count":9,"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/posts\/38972\/revisions"}],"predecessor-version":[{"id":39352,"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/posts\/38972\/revisions\/39352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/media\/38990"}],"wp:attachment":[{"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=38972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=38972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=38972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}