{"id":5805,"date":"2012-01-11T10:23:36","date_gmt":"2012-01-11T09:23:36","guid":{"rendered":"http:\/\/www.ce-illkirch.fr\/wordpress\/?p=5805"},"modified":"2012-01-11T10:23:36","modified_gmt":"2012-01-11T09:23:36","slug":"completement-livres","status":"publish","type":"post","link":"https:\/\/www.ce-illkirch.fr\/wordpress\/2012\/01\/non-classe\/completement-livres\/","title":{"rendered":"COMPLETEMENT LIVRES !"},"content":{"rendered":"<p><a href=\"http:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/galette.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-5806\" title=\"galette\" src=\"http:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/galette.jpg\" alt=\"\" width=\"130\" height=\"98\" \/><\/a>EveLine vous donne rendez-vous \u00e0 l&rsquo;Espace Image (\u00e0 c\u00f4t\u00e9 de la biblioth\u00e8que) le Vendredi 13 Janvier 2012 \u00e0 partir de 12h30.<\/p>\n<p>Elle vous d\u00e9voilera les r\u00e9sultats des votes ainsi que la nouvelle s\u00e9lection de cette 4 \u00e8me \u00e9dition autour d&rsquo;une galette des rois et de bulles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EveLine vous donne rendez-vous \u00e0 l&rsquo;Espace Image (\u00e0 c\u00f4t\u00e9 de la biblioth\u00e8que) le Vendredi 13 Janvier 2012 \u00e0 partir de 12h30. Elle vous d\u00e9voilera les r\u00e9sultats des votes ainsi que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-5805","post","type-post","status-publish","format-standard","hentry","category-bibliotheque","category-non-classe"],"publishpress_future_action":{"enabled":false,"date":"2026-07-23 01:31:24","action":"category","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/posts\/5805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=5805"}],"version-history":[{"count":0,"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/posts\/5805\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=5805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=5805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=5805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}