{"id":7676,"date":"2012-10-15T07:50:08","date_gmt":"2012-10-15T06:50:08","guid":{"rendered":"http:\/\/www.ce-illkirch.fr\/wordpress\/?p=7676"},"modified":"2012-10-15T07:50:08","modified_gmt":"2012-10-15T06:50:08","slug":"soutenez-les-coureurs-alcatel-lucent-au-marathon-de-strasbourg-et-gagnez","status":"publish","type":"post","link":"https:\/\/www.ce-illkirch.fr\/wordpress\/2012\/10\/non-classe\/soutenez-les-coureurs-alcatel-lucent-au-marathon-de-strasbourg-et-gagnez\/","title":{"rendered":"Soutenez les coureurs Alcatel Lucent au MARATHON de Strasbourg et GAGNEZ&#8230;."},"content":{"rendered":"<div><a href=\"http:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/marathon.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-7684\" title=\"marathon\" src=\"http:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/marathon-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Dans le but de montrer le dynamisme de notre Club Sportif, la tr\u00e8s active section running et le Comit\u00e9 s\u2019appuie sur le 1 er Marathon de Strasbourg EUROdistrict,<\/div>\n<div>(qui passera Dimanche 28 Octobre devant le site Alcatel Lucent ) pour lancer un jeu ouvert aux sportifs du site et aux personnels Alcatel ou cotisants du CE.<\/div>\n<div><span style=\"font-size: x-small; color: #000080; font-family: FuturaA Bk BT, sans-serif;\">\u00a0<\/span><\/div>\n<div><span style=\"font-size: x-small; color: #000080;\"><strong>\u00a0<a href=\"http:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/my_first_marathon.pdf\" target=\"_blank\"> <\/a><\/strong><a href=\"http:\/\/www.ce-illkirch.fr\/wordpress\/wp-content\/uploads\/my_first_marathon.pdf\" target=\"_blank\"><strong>\u2018\u2019<\/strong><strong> My First Marathon<\/strong><strong>\u2019\u2019<\/strong><strong> <\/strong><\/a>Estimer le temps du meilleur coureur du site au 1er marathon de Strasbourg.<\/span><\/div>\n<div>Ce petit jeu va permettre de gagner une montre GPS Garmin en soutenant nos 14 marathoniens sans n\u00e9cessairement courir eux m\u00eame les 42 km 195\u00a0 \u00a0:=).<\/div>\n<div>\u00a0<\/div>\n<div>Pour affiner le pronostique,\u00a0n\u2019h\u00e9sitez pas \u00e0 rencontrer nos \u2018Runneurs\u2019\u00a0 voire m\u00eame nos Triathl\u00e8tes.<\/div>\n<div>Sportivement<\/div>\n<div>Jacques<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dans le but de montrer le dynamisme de notre Club Sportif, la tr\u00e8s active section running et le Comit\u00e9 s\u2019appuie sur le 1 er Marathon de Strasbourg EUROdistrict, (qui passera [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45,1,29],"tags":[],"class_list":["post-7676","post","type-post","status-publish","format-standard","hentry","category-athle","category-non-classe","category-scabsi"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 08:22:18","action":"category","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/posts\/7676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=7676"}],"version-history":[{"count":0,"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/posts\/7676\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=7676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=7676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ce-illkirch.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=7676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}